{"id":30,"count":1,"description":"","link":"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/","name":"Fine Lines &amp; Wrinkles","slug":"fine-lines-wrinkles","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fine Lines &amp; Wrinkles Archives - Blu Monarch Skin Studio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fine Lines &amp; Wrinkles Archives - Blu Monarch Skin Studio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/\" \/>\n<meta property=\"og:site_name\" content=\"Blu Monarch Skin Studio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/category\\\/fine-lines-wrinkles\\\/\",\"url\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/category\\\/fine-lines-wrinkles\\\/\",\"name\":\"Fine Lines &amp; Wrinkles Archives - Blu Monarch Skin Studio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/category\\\/fine-lines-wrinkles\\\/#breadcrumb\"},\"inLanguage\":\"en\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/category\\\/fine-lines-wrinkles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fine Lines &amp; Wrinkles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/\",\"name\":\"Blu Monarch Skin Studio\",\"description\":\"Med Spa Skin Studio  - San Mateo\",\"publisher\":{\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/#organization\"},\"alternateName\":\"Blu Monarch Med Spa\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/#organization\",\"name\":\"Blu Monarch\",\"alternateName\":\"Blu Monarch Skin Studio\",\"url\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/bm-logo2.svg\",\"contentUrl\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/bm-logo2.svg\",\"width\":273,\"height\":251,\"caption\":\"Blu Monarch\"},\"image\":{\"@id\":\"https:\\\/\\\/blumonarchskinstudio.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/blumonarchskin\\\/\",\"https:\\\/\\\/www.instagram.com\\\/blumonarchskinstudio\\\/?hl=en\",\"https:\\\/\\\/www.tiktok.com\\\/discover\\\/blu-monarch-skin-studio-san-mateo\",\"https:\\\/\\\/www.yelp.com\\\/biz\\\/blu-monarch-skin-studio-san-mateo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fine Lines &amp; Wrinkles Archives - Blu Monarch Skin Studio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/","og_locale":"en_US","og_type":"article","og_title":"Fine Lines &amp; Wrinkles Archives - Blu Monarch Skin Studio","og_url":"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/","og_site_name":"Blu Monarch Skin Studio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/","url":"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/","name":"Fine Lines &amp; Wrinkles Archives - Blu Monarch Skin Studio","isPartOf":{"@id":"https:\/\/blumonarchskinstudio.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/#breadcrumb"},"inLanguage":"en"},{"@type":"BreadcrumbList","@id":"https:\/\/blumonarchskinstudio.com\/blog\/category\/fine-lines-wrinkles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blumonarchskinstudio.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Fine Lines &amp; Wrinkles"}]},{"@type":"WebSite","@id":"https:\/\/blumonarchskinstudio.com\/blog\/#website","url":"https:\/\/blumonarchskinstudio.com\/blog\/","name":"Blu Monarch Skin Studio","description":"Med Spa Skin Studio  - San Mateo","publisher":{"@id":"https:\/\/blumonarchskinstudio.com\/blog\/#organization"},"alternateName":"Blu Monarch Med Spa","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blumonarchskinstudio.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/blumonarchskinstudio.com\/blog\/#organization","name":"Blu Monarch","alternateName":"Blu Monarch Skin Studio","url":"https:\/\/blumonarchskinstudio.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/blumonarchskinstudio.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/blumonarchskinstudio.com\/wp-content\/uploads\/2020\/03\/bm-logo2.svg","contentUrl":"https:\/\/blumonarchskinstudio.com\/wp-content\/uploads\/2020\/03\/bm-logo2.svg","width":273,"height":251,"caption":"Blu Monarch"},"image":{"@id":"https:\/\/blumonarchskinstudio.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/blumonarchskin\/","https:\/\/www.instagram.com\/blumonarchskinstudio\/?hl=en","https:\/\/www.tiktok.com\/discover\/blu-monarch-skin-studio-san-mateo","https:\/\/www.yelp.com\/biz\/blu-monarch-skin-studio-san-mateo"]}]}},"_links":{"self":[{"href":"https:\/\/blumonarchskinstudio.com\/blog\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blumonarchskinstudio.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blumonarchskinstudio.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blumonarchskinstudio.com\/blog\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}